{"id":817,"date":"2023-07-11T10:37:11","date_gmt":"2023-07-11T10:37:11","guid":{"rendered":"https:\/\/www.lasqolqas.com\/?p=11025"},"modified":"2025-04-20T23:00:38","modified_gmt":"2025-04-20T23:00:38","slug":"cruzar-oceanos-slow-travel-consejos","status":"publish","type":"post","link":"https:\/\/lasqolqas.com\/es\/blog\/crossing-oceans-slow-travel-tips\/","title":{"rendered":"Atravesar los oc\u00e9anos - Los consejos de Slow Travel 2023"},"content":{"rendered":"<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.crossingoceans.net\/single-post\/23-incredible-slow-travel-tips-to-consider-in-2023#viewer-6nrc1\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Leer el art\u00edculo<\/a><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>23 Incre\u00edbles consejos de slow travel a tener en cuenta en tus planes de viaje para 2023.<\/p>","protected":false},"author":4,"featured_media":818,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/lasqolqas.com\/es\/wp-json\/wp\/v2\/posts\/817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasqolqas.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasqolqas.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasqolqas.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lasqolqas.com\/es\/wp-json\/wp\/v2\/comments?post=817"}],"version-history":[{"count":1,"href":"https:\/\/lasqolqas.com\/es\/wp-json\/wp\/v2\/posts\/817\/revisions"}],"predecessor-version":[{"id":984,"href":"https:\/\/lasqolqas.com\/es\/wp-json\/wp\/v2\/posts\/817\/revisions\/984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasqolqas.com\/es\/wp-json\/wp\/v2\/media\/818"}],"wp:attachment":[{"href":"https:\/\/lasqolqas.com\/es\/wp-json\/wp\/v2\/media?parent=817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasqolqas.com\/es\/wp-json\/wp\/v2\/categories?post=817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasqolqas.com\/es\/wp-json\/wp\/v2\/tags?post=817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}